{"id":892,"date":"2018-03-06T12:57:46","date_gmt":"2018-03-06T11:57:46","guid":{"rendered":"http:\/\/news.aconity3d.com\/?p=892\/"},"modified":"2018-03-06T13:01:43","modified_gmt":"2018-03-06T12:01:43","slug":"aconity3d-ist-gruendungsnetwerkpartner-fuer-gedruckte-metallische-ersatzteile","status":"publish","type":"post","link":"https:\/\/news.aconity3d.com\/de\/aconity3d-ist-gruendungsnetwerkpartner-fuer-gedruckte-metallische-ersatzteile\/","title":{"rendered":"Aconity3D ist Gr\u00fcndungsnetwerkpartner f\u00fcr gedruckte metallische Ersatzteile"},"content":{"rendered":"<p><span id=\"result_box\" class=\"\" lang=\"de\"><span class=\"\">Im Rahmen der industriellen Anwendung von AM-Teilen aus Metall werden Ersatzteile immer wichtiger, um den ineffizienten Bestand in vielen verschiedenen Anwendungsbereichen zu reduzieren.<\/span><\/span><\/p>\n<p>Innovation und Entwicklung sind wichtige Bestandteile der Firmentradition von Aconity3D. Um immer am Puls der Zeit zu sein, besteht im Rahmen des Kooperationsnetzwerks SparesAMx eine enge Zusammenarbeit mit weiteren innovativen Unternehmen und Forschungseinrichtungen. Gemeinsam mit anderen Netzwerkpartnern entwickelt Aconity3D im Rahmen von Forschungs- und Entwicklungsprojekten innovative und nachhaltige L\u00f6sungen, um die additive Fertigung auf ein neues Leistungsniveau zu heben. Weitere Informationen finden Sie unter: <a href=\"http:\/\/www.sparesamx.de\">www.sparesamx.de <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Rahmen der industriellen Anwendung von AM-Teilen aus Metall werden Ersatzteile immer wichtiger, um den ineffizienten Bestand in vielen verschiedenen Anwendungsbereichen zu reduzieren. Innovation und Entwicklung sind wichtige Bestandteile der Firmentradition von Aconity3D. Um immer am Puls der Zeit zu sein, besteht im Rahmen des Kooperationsnetzwerks SparesAMx eine enge Zusammenarbeit mit weiteren innovativen Unternehmen und<a href=\"https:\/\/news.aconity3d.com\/de\/aconity3d-ist-gruendungsnetwerkpartner-fuer-gedruckte-metallische-ersatzteile\/\"> &hellip; <\/a><\/p>\n","protected":false},"author":4,"featured_media":889,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"_links":{"self":[{"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/posts\/892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/comments?post=892"}],"version-history":[{"count":7,"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/posts\/892\/revisions"}],"predecessor-version":[{"id":900,"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/posts\/892\/revisions\/900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/media\/889"}],"wp:attachment":[{"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/media?parent=892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/categories?post=892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.aconity3d.com\/de\/wp-json\/wp\/v2\/tags?post=892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}